{"id":3674,"date":"2025-05-10T16:53:10","date_gmt":"2025-05-10T14:53:10","guid":{"rendered":"https:\/\/rhl-dart-test.tobiassmann-it.de\/?page_id=3674"},"modified":"2025-09-02T21:38:26","modified_gmt":"2025-09-02T19:38:26","slug":"saison-2010-11","status":"publish","type":"page","link":"https:\/\/rhl-dart.de\/index.php\/saison-2010-11\/","title":{"rendered":"Saison 2010\/11"},"content":{"rendered":"\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f3e5cb0b\"><h2 class=\"uagb-heading-text\">Spielplan<\/h2><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"656\" height=\"442\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Spielplan_oben_1.jpg\" alt=\"\" class=\"wp-image-403\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Spielplan_oben_2.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Spielplan_unten_1.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Spielplan_unten_2.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-35e99b1f\"><h2 class=\"uagb-heading-text\">Tabelle<\/h2><\/div>\n\n\n\n<table id=\"tablepress-79\" class=\"tablepress tablepress-id-79\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Platz<\/th><th class=\"column-2\">Team<\/th><th class=\"column-3\">Spiele<\/th><th class=\"column-4\">S\u00e4tze<\/th><th class=\"column-5\">Legs<\/th><th class=\"column-6\">Punkte<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">1.DC Kastellaun<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">189:91<\/td><td class=\"column-5\">646:430<\/td><td class=\"column-6\">36<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">Dart Union M\u00fclhofen<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">166:114<\/td><td class=\"column-5\">605:465<\/td><td class=\"column-6\">34<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">DC Coblenz I<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">162:118<\/td><td class=\"column-5\">601:468<\/td><td class=\"column-6\">29<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">DC Coblenz II<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">128:152<\/td><td class=\"column-5\">523:588<\/td><td class=\"column-6\">19<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">DSC Kastanie 1<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">135:145<\/td><td class=\"column-5\">541:549<\/td><td class=\"column-6\">18<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">DSC Bandits<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">140:140<\/td><td class=\"column-5\">524:544<\/td><td class=\"column-6\">18<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">Team Joker<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">118:162<\/td><td class=\"column-5\">500:598<\/td><td class=\"column-6\">8<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">DSC Kastanie 2<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">82:198<\/td><td class=\"column-5\">369:670<\/td><td class=\"column-6\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-79 from cache -->\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f16ae872\"><h2 class=\"uagb-heading-text\">Rangliste<\/h2><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"568\" height=\"556\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Rangliste_oben.jpg\" alt=\"\" class=\"wp-image-407\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Rangliste_mitte.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/rhl-dart.de\/wp-content\/uploads\/2020\/07\/2010_2011_Rangliste_unten.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ceee2ec2\"><h2 class=\"uagb-heading-text\">Bestleistungen<\/h2><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Spielplan Tabelle Rangliste Bestleistungen<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":86,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-3674","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Tobias Assmann","author_link":"https:\/\/rhl-dart.de\/index.php\/author\/testuser\/"},"uagb_comment_info":0,"uagb_excerpt":"Spielplan Tabelle Rangliste Bestleistungen","_links":{"self":[{"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/pages\/3674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/comments?post=3674"}],"version-history":[{"count":2,"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/pages\/3674\/revisions"}],"predecessor-version":[{"id":3895,"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/pages\/3674\/revisions\/3895"}],"wp:attachment":[{"href":"https:\/\/rhl-dart.de\/index.php\/wp-json\/wp\/v2\/media?parent=3674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}